{"id":8,"count":0,"description":"","link":"https:\/\/fliwer.selvadigital.dev\/es\/category\/sin-categorizar\/","name":"Sin categorizar","slug":"sin-categorizar","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/fliwer.selvadigital.dev\/es\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fliwer.selvadigital.dev\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/fliwer.selvadigital.dev\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/fliwer.selvadigital.dev\/es\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}